{"id":5411,"date":"2016-08-09T14:28:02","date_gmt":"2016-08-09T14:28:02","guid":{"rendered":"http:\/\/discoveryartfair.com\/de\/?p=5411"},"modified":"2017-07-09T14:28:49","modified_gmt":"2017-07-09T14:28:49","slug":"petula-girndts-monochromatische-welt-der-maennlichen-sinnlichkeit","status":"publish","type":"post","link":"https:\/\/discoveryartfair.com\/de\/petula-girndts-monochromatische-welt-der-maennlichen-sinnlichkeit\/","title":{"rendered":"Petula Girndts Monochromatische Welt der m\u00e4nnlichen Sinnlichkeit"},"content":{"rendered":"<p>Die in Berlin lebende K\u00fcnstlerin <strong>Petula<\/strong> <strong>Girndt<\/strong> setzt sich in ihren provokativen und gleichzeitig h\u00f6chst anspruchsvollen Fotografien mit der m\u00e4nnlichen Seite von Sinnlichkeit auseinander. <em>\u201eJeder hat etwas, dass ihn gl\u00fchen l\u00e4sst\u201c\u00a9<\/em> \u00e4u\u00dfert sich die K\u00fcnstlerin \u00fcber die menschliche Natur. Sie ist eine sorgf\u00e4ltige Beobachterin und konzentriert sich auf Gef\u00fchle wie Leidenschaft und Begierde. Dabei akzentuiert sie die unmittelbare Energie, Bewegung und die Gef\u00fchle des Augenblicks und nutz dabei oft die Unsch\u00e4rfe  als k\u00fcnstlerische Ausdrucksform , um dem Betrachter etwas auf Abstand zu halten und ihm die M\u00f6glichkeit zu geben, die Atmosph\u00e4re auf dem Bild zu f\u00fchlen. Ihre Fotografien haben eine stark poetische Komponente. Die Idee hinter ihren Werken geht viel weiter als \u00fcber die reine Darstellung des m\u00e4nnlichen K\u00f6rpers. Die K\u00fcnstlerin offenbart sich selbst und ihre Gef\u00fchle durch die Fotografien der m\u00e4nnlichen  Modelle. Einige Werke von ihr wurden mittlerweile nicht nur in Deutschland, sondern bereits europaweit und in Asien ausgestellt. Zeitgleich zu ihrer Deb\u00fctausstellung auf der K\u00f6lner Liste hat Petula Girndt ein Fotobuch fertig gestellt an dem sie 2 Jahre arbeitete. Es sind die Bilder aus diesem Buch, die in ihrer ausdrucksstarken <em>M\u00e4nner<\/em> Serie zu finden sind.<\/p>\n<div class=\"separator\"><\/div>\n<h2>Auseinandersetzung mit Bildkompositionen<\/h2>\n<p>In unserem Gespr\u00e4ch mit der Fotografin sind wir n\u00e4her auf ihre Erfahrungen mit Galerien und Ausstellungen in Berlin wie z.B. der Berliner Liste eingegangen, wir haben \u00fcber ihre k\u00fcnstlerische Vision und ihr Pl\u00e4ne f\u00fcr die Zukunft gesprochen. Es ist offensichtlich, dass die K\u00fcnstlerin in ihren Fotografien eine gewisse Wandlung \u00fcber die Zeit durchgemacht hat.  Auf ihren  fr\u00fcheren Werke waren vor allem weibliche Models zu sehen w\u00e4hrend ihre neueren Arbeiten sich haupts\u00e4chlich auf Fotografien des  m\u00e4nnlichen K\u00f6rper s konzentrieren. <em>Ich wollte ein einzigartiges Fotobuch und eine entsprechende Bilderserie  machen, um meine Seele mit all ihren Feinheiten, Leidenschaften und Abgr\u00fcnden, durch M\u00e4nner zeigen. Es war schon eine Art  Experiment.  Ich wollte tiefer gehen. Jede Intensit\u00e4t dastellen, die ich f\u00fchle. Mit Frauen w\u00e4re das zu banal gewesen. Ich hatte von klein auf immer einen besonders einfach Zugang zu m\u00e4nnlichen Wesen. Mit Frauen ist das schwieriger f\u00fcr mich.  Ich bin mit meinem Zwillingsbruder und seinen Freunden aufgewachsen und auch als Erwachsene bevorzuge  ich die Gesellschaft von m\u00e4nnlichen Freunden, bis heute. Ich mag M\u00e4nner einfach sehr !!  und: Ich bin immer \u201ein Love\u201c<\/em> beschreibt die K\u00fcnstlerin l\u00e4chelnd den \u00e4u\u00dferst emotionalen Hintergrund ihrer <em>M\u00e4nner<\/em> Serie Girndts k\u00fcnstlerischer Anspruch ist im Laufe der Jahre gleich hoch  geblieben, er hat sich eher noch gesteigert. Ihre fr\u00fcheren fotografischen Arbeiten mit Frauen waren bereits monochromatisch  mit dem Fokus auf Gesten und starke Emotionen  und zeigten bereits dort ihre eigene Sprache. <\/p>\n<p>Die K\u00fcnstlerin erkl\u00e4rt dies folgenderma\u00dfen: <em>Ich habe mit der analogen Fotografie und schwarz-wei\u00df Filmen begonnnen, daher war ich nie wirklich von der Farbfotografie beeindruckt.  F\u00fcr meine Empfinden bekommt das Bild in schwarz\/wei\u00df gemeinsam mit der Unsch\u00e4rfe  eine besondere Dramatik die ich zeigen m\u00f6chte. mehr als in Farbe. Es gibt bei meinen Shootings immer ein bestimmtes Thema , einen Leitfaden, aber es wird dennoch genug Gestaltungsraum f\u00fcr meine  k\u00fcnstlerische Freiheit und die meiner Models einger\u00e4umt. Jedes Shooting ist eine andere Reise und ich m\u00f6chte nicht jedes kleinste Detail planen, weil es sonst die Intensit\u00e4t und den Rausch zerst\u00f6rt, die ich in den Bildern suche. Mein Focus liegt stets nur  auf dem perfekten Augenblick.<\/em> Ein weitere Besonderheit an  Girndts  Arbeit ist, dass sie keine Editionen  produziert, was bedeutet dass all ihre Werke Originale sind, \u00e4hnlich wie Malereien oder Zeichnungen. <\/p>\n<div class=\"separator\"><\/div>\n<h2>Teilnahme an der Berliner Liste 2016<\/h2>\n<p>Wenn es darum geht in Berlin eine Galerie zu finden um dort Fotografien auszustellen, glaubt Girndt  es kommt auch darauf an, zur richtigen zeit am richtigen Ort zu sein un den richtigen Menschen zu treffen\u2026 und es sei  auch ein bisschen Schicksal sagt sie. <em>Die Berliner Kunstszene  hat schon immer  schon pulsiert. Es gibt viele wunderbare und inspirierende K\u00fcnstler in Berlin, aber gleichzeitig auch viele \u201eFl\u00fcchtiges\u201c  meint die K\u00fcnstlerin.<\/em> Sie ist eine aktive Ausstellerin und hatte bereits die ihre Erfahrung auf der K\u00f6lner Liste und freut sich nun auf die Berliner Liste 2016, die im September  in dem unvergleichlichen Veranstaltungsort Kraftwerk in Mitte stattfinden wird. <em>Ich freue mich schon sehr ausgew\u00e4hlte  Arbeiten von mir zu zeigen und andere K\u00fcnstler zu treffen, genauso wie ich es bereits auf der K\u00f6lner Liste getan habe. Es war eine wirklich inspirierende Kunstmesse, wir hatten sehr viel Spa\u00df.  Weiterhin im September\/Oktober werde  ich mit bekannten K\u00fcnstlern in  einer  Kunstgalerie  in D\u00fcsseldorf  ausstellen. Nat\u00fcrlich beginne ich  auch derzeit mit einem neuen Projekt,<\/em> \u00e4u\u00dfert sich  Girndt  \u00fcber ihre Pl\u00e4ne. Zus\u00e4tzlich zu ihrer Hauptleidenschaft der Fotografie ist die K\u00fcnstlerin auch an anderen Medien interessiert, was auch der Grund ist warum sie sich so auf die Berliner Liste und den vielseitigen Teilnehmern freut, die sich eben nicht nur auf ein traditionelles Medium beschr\u00e4nken. <em>Mein Herz schl\u00e4gt f\u00fcr Kurzfilme, damit experimentiere ich zwischendurch gern.aber auch Installationen, sowie  finde ich hochinteressant,<\/em> gibt uns die K\u00fcnstlerin preis.  <\/p>\n<div class=\"separator\"><\/div>\n<h2>Viel Leidenschaft, Enthusiasmus und ein ausgezeichnetes Netzwerk<\/h2>\n<p>Am Ende haben wir die K\u00fcnstlerin nach ihrer Einsch\u00e4tzung zum Einfluss von Sozialen Medien oder Fotografie Plattformen auf den Lifestyle eines Fotografen gefragt sowie nach ihrem Rat f\u00fcr Amateure, die es noch nicht geschafft haben ihre Werke zu pr\u00e4sentieren. <em>Um ehrlich zu sein glaube ich, dass ich mehr Zeit aufwenden m\u00fcsste, um meine online Identit\u00e4t und sozialen Profile aufzubauen und zu pflegen. Es ist ein wichtiger Ansatz, wenngleich ich ihn nicht unbedingt mag. Ich bin einfach kein Genie wenn es um Marketingstrategien geht,<\/em> es liegt mir absolut gar nicht gibt die K\u00fcnstlerin offen zu. <em>Ich will Bilder machen, sonst nichts. Es ist jedenfalls wichtig f\u00fcr jeden jungen K\u00fcnstler  eine gut funktionierendes Netzwerk aufzubauen. Ansonsten viel Leidenschaft und Mut und niemals aufgeben. <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die in Berlin lebende K\u00fcnstlerin Petula Girndt setzt sich in ihren provokativen und gleichzeitig h\u00f6chst anspruchsvollen Fotografien mit der m\u00e4nnlichen Seite von Sinnlichkeit auseinander. \u201eJeder hat etwas, dass ihn gl\u00fchen l\u00e4sst\u201c\u00a9 \u00e4u\u00dfert sich die K\u00fcnstlerin \u00fcber die menschliche Natur. Sie ist eine sorgf\u00e4ltige Beobachterin und konzentriert sich auf Gef\u00fchle wie Leidenschaft und Begierde. Dabei akzentuiert [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":5409,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[107],"tags":[145,151],"class_list":["post-5411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert","tag-interview","tag-petula-girndt"],"acf":[],"_links":{"self":[{"href":"https:\/\/discoveryartfair.com\/de\/wp-json\/wp\/v2\/posts\/5411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/discoveryartfair.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/discoveryartfair.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/discoveryartfair.com\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/discoveryartfair.com\/de\/wp-json\/wp\/v2\/comments?post=5411"}],"version-history":[{"count":0,"href":"https:\/\/discoveryartfair.com\/de\/wp-json\/wp\/v2\/posts\/5411\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/discoveryartfair.com\/de\/wp-json\/wp\/v2\/media\/5409"}],"wp:attachment":[{"href":"https:\/\/discoveryartfair.com\/de\/wp-json\/wp\/v2\/media?parent=5411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/discoveryartfair.com\/de\/wp-json\/wp\/v2\/categories?post=5411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/discoveryartfair.com\/de\/wp-json\/wp\/v2\/tags?post=5411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}